{"id":8066,"date":"2021-08-20T18:22:54","date_gmt":"2021-08-20T16:26:23","guid":{"rendered":"https:\/\/bodegasbaigorri.com\/?post_type=product&#038;p=8066"},"modified":"2023-11-22T17:46:37","modified_gmt":"2023-11-22T16:46:37","slug":"baigorri-finca-la-canoca","status":"publish","type":"product","link":"https:\/\/bodegasbaigorri.com\/en\/producto\/baigorri-finca-la-canoca\/","title":{"rendered":"Baigorri Finca La Canoca"},"content":{"rendered":"<p>This wine is a tribute to a vineyard in a valley where mostiy Tempranillo grapes are grown. Only 5,000 bottles per vintage are produced and the current one is the first on the market. The age of the vineyard is irrelevant if we think about the characteristics of this calcareous soil and its altitude of more than 600 meters. It is one of the last vineyards to be harvested precisely because time does not run so fast in the valley and its harvest requires care and dedication. After a manual harvest the bunches are collected in boxes and sorted out. Afterwards, an alcoholic fermentation is performed with native yeasts in 5,000-liter French oak vats, whereas the malolactic fermentation happens in barrels from centenary oaks at 20 degrees.<\/p>\n<h3><strong>Vineyards<\/strong><\/h3>\n<p>Red wine made with Tempranillo grapes from vines planted in 1960. The vineyard is situated at an altitude of 640m on the slopes of the Tolo\u00f1o mountain chain, with a North-South facing plots and clay-calcareous soil. It is made in 225 litres barrels in a traditional way with destemmed grapes and whole grains. Subsequently dry ice is used to develop an intercellular maceration as long as possible. During the alcoholic fermentation, which lasts 30 days, the juice is pumped manually. Afterwards, the wine is transferred to new French oak barrels for a malolactic fermentation at 20 degrees.<\/p>\n<h3><strong>Tasting note<\/strong><\/h3>\n<p>Intense ruby colored wine with aromas of ripe fruit and spices. Its balance and freshness on the palate are positively surprising. Its unctuousness and its singular style stand out, with great potential in all its complexity is a true reflection of the terroir, which makes Finca La Canoca unique.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><a href=\"https:\/\/bodegasbaigorri.com\/wp-content\/uploads\/2023\/11\/Finca-La-Canoca-EN.pdf\" target=\"_blank\" rel=\"noopener\">Tasting sheet<\/a><\/p>\n","protected":false},"featured_media":7862,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[81],"product_tag":[],"class_list":{"0":"post-8066","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-baigorri-en","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Baigorri Finca La Canoca - Bodegas Baigorri<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bodegasbaigorri.com\/en\/producto\/baigorri-finca-la-canoca\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Baigorri Finca La Canoca - Bodegas Baigorri\" \/>\n<meta property=\"og:description\" content=\"Tasting sheet\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bodegasbaigorri.com\/en\/producto\/baigorri-finca-la-canoca\/\" \/>\n<meta property=\"og:site_name\" content=\"Bodegas Baigorri\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-22T16:46:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bodegasbaigorri.com\/wp-content\/uploads\/2021\/07\/baigorri-finca-la-canoca1x1.jpg?_t=1700671598\" \/>\n\t<meta property=\"og:image:width\" content=\"659\" \/>\n\t<meta property=\"og:image:height\" content=\"659\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bodegasbaigorri.com\\\/en\\\/producto\\\/baigorri-finca-la-canoca\\\/\",\"url\":\"https:\\\/\\\/bodegasbaigorri.com\\\/en\\\/producto\\\/baigorri-finca-la-canoca\\\/\",\"name\":\"Baigorri Finca La Canoca - Bodegas Baigorri\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bodegasbaigorri.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bodegasbaigorri.com\\\/en\\\/producto\\\/baigorri-finca-la-canoca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bodegasbaigorri.com\\\/en\\\/producto\\\/baigorri-finca-la-canoca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bodegasbaigorri.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/baigorri-finca-la-canoca1x1.jpg\",\"datePublished\":\"2021-08-20T16:26:23+00:00\",\"dateModified\":\"2023-11-22T16:46:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bodegasbaigorri.com\\\/en\\\/producto\\\/baigorri-finca-la-canoca\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bodegasbaigorri.com\\\/en\\\/producto\\\/baigorri-finca-la-canoca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/bodegasbaigorri.com\\\/en\\\/producto\\\/baigorri-finca-la-canoca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bodegasbaigorri.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/baigorri-finca-la-canoca1x1.jpg\",\"contentUrl\":\"https:\\\/\\\/bodegasbaigorri.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/baigorri-finca-la-canoca1x1.jpg\",\"width\":2560,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bodegasbaigorri.com\\\/en\\\/producto\\\/baigorri-finca-la-canoca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/bodegasbaigorri.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Baigorri Finca La Canoca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bodegasbaigorri.com\\\/#website\",\"url\":\"https:\\\/\\\/bodegasbaigorri.com\\\/\",\"name\":\"Bodegas Baigorri\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/bodegasbaigorri.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bodegasbaigorri.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bodegasbaigorri.com\\\/#organization\",\"name\":\"Bodegas Baigorri\",\"url\":\"https:\\\/\\\/bodegasbaigorri.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/bodegasbaigorri.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bodegasbaigorri.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/logo-blanco.png\",\"contentUrl\":\"https:\\\/\\\/bodegasbaigorri.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/logo-blanco.png\",\"width\":80,\"height\":60,\"caption\":\"Bodegas Baigorri\"},\"image\":{\"@id\":\"https:\\\/\\\/bodegasbaigorri.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Baigorri Finca La Canoca - Bodegas Baigorri","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bodegasbaigorri.com\/en\/producto\/baigorri-finca-la-canoca\/","og_locale":"en_US","og_type":"article","og_title":"Baigorri Finca La Canoca - Bodegas Baigorri","og_description":"Tasting sheet","og_url":"https:\/\/bodegasbaigorri.com\/en\/producto\/baigorri-finca-la-canoca\/","og_site_name":"Bodegas Baigorri","article_modified_time":"2023-11-22T16:46:37+00:00","og_image":[{"width":659,"height":659,"url":"https:\/\/bodegasbaigorri.com\/wp-content\/uploads\/2021\/07\/baigorri-finca-la-canoca1x1.jpg?_t=1700671598","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bodegasbaigorri.com\/en\/producto\/baigorri-finca-la-canoca\/","url":"https:\/\/bodegasbaigorri.com\/en\/producto\/baigorri-finca-la-canoca\/","name":"Baigorri Finca La Canoca - Bodegas Baigorri","isPartOf":{"@id":"https:\/\/bodegasbaigorri.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bodegasbaigorri.com\/en\/producto\/baigorri-finca-la-canoca\/#primaryimage"},"image":{"@id":"https:\/\/bodegasbaigorri.com\/en\/producto\/baigorri-finca-la-canoca\/#primaryimage"},"thumbnailUrl":"https:\/\/bodegasbaigorri.com\/wp-content\/uploads\/2021\/07\/baigorri-finca-la-canoca1x1.jpg","datePublished":"2021-08-20T16:26:23+00:00","dateModified":"2023-11-22T16:46:37+00:00","breadcrumb":{"@id":"https:\/\/bodegasbaigorri.com\/en\/producto\/baigorri-finca-la-canoca\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bodegasbaigorri.com\/en\/producto\/baigorri-finca-la-canoca\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/bodegasbaigorri.com\/en\/producto\/baigorri-finca-la-canoca\/#primaryimage","url":"https:\/\/bodegasbaigorri.com\/wp-content\/uploads\/2021\/07\/baigorri-finca-la-canoca1x1.jpg","contentUrl":"https:\/\/bodegasbaigorri.com\/wp-content\/uploads\/2021\/07\/baigorri-finca-la-canoca1x1.jpg","width":2560,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/bodegasbaigorri.com\/en\/producto\/baigorri-finca-la-canoca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/bodegasbaigorri.com\/en\/shop\/"},{"@type":"ListItem","position":2,"name":"Baigorri Finca La Canoca"}]},{"@type":"WebSite","@id":"https:\/\/bodegasbaigorri.com\/#website","url":"https:\/\/bodegasbaigorri.com\/","name":"Bodegas Baigorri","description":"","publisher":{"@id":"https:\/\/bodegasbaigorri.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bodegasbaigorri.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/bodegasbaigorri.com\/#organization","name":"Bodegas Baigorri","url":"https:\/\/bodegasbaigorri.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/bodegasbaigorri.com\/#\/schema\/logo\/image\/","url":"https:\/\/bodegasbaigorri.com\/wp-content\/uploads\/2019\/09\/logo-blanco.png","contentUrl":"https:\/\/bodegasbaigorri.com\/wp-content\/uploads\/2019\/09\/logo-blanco.png","width":80,"height":60,"caption":"Bodegas Baigorri"},"image":{"@id":"https:\/\/bodegasbaigorri.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/bodegasbaigorri.com\/en\/wp-json\/wp\/v2\/product\/8066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bodegasbaigorri.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bodegasbaigorri.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/bodegasbaigorri.com\/en\/wp-json\/wp\/v2\/comments?post=8066"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bodegasbaigorri.com\/en\/wp-json\/wp\/v2\/media\/7862"}],"wp:attachment":[{"href":"https:\/\/bodegasbaigorri.com\/en\/wp-json\/wp\/v2\/media?parent=8066"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/bodegasbaigorri.com\/en\/wp-json\/wp\/v2\/product_brand?post=8066"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bodegasbaigorri.com\/en\/wp-json\/wp\/v2\/product_cat?post=8066"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bodegasbaigorri.com\/en\/wp-json\/wp\/v2\/product_tag?post=8066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}